{"id":293,"date":"2022-05-12T15:37:04","date_gmt":"2022-05-12T15:37:04","guid":{"rendered":"https:\/\/library.bustmold.com\/?page_id=293"},"modified":"2022-05-31T13:19:25","modified_gmt":"2022-05-31T13:19:25","slug":"aspergillus-ochraceus","status":"publish","type":"page","link":"https:\/\/library.bustmold.com\/fr\/aspergillus\/aspergillus-ochraceus\/","title":{"rendered":"Aspergillus ochraceus"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En tant que membre du genre <em>Aspergillus<\/em> (qui regroupe environ 200 esp\u00e8ces de champignons dans le monde), <em>Aspergillus Ochraceus<\/em> est une esp\u00e8ce de moisissure que l\u2019on rencontre le plus souvent dans la terre, sur le grains ainsi que sur les aliments secs. Ce type de moisissure produit une mycotoxine, l\u2019ochratoxine A (OTA) qui est assez puissante et qui peut provoquer de graves l\u00e9sions r\u00e9nales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Etant donn\u00e9 que ses spores peuvent facilement entrer en suspension dans l\u2019air, une colonie d\u2019<em>Aspergillus Ochraceus<\/em> peut facilement se d\u00e9velopper sur \u00e0 peu pr\u00e8s n\u2019importe quelle surface, particuli\u00e8rement dans les environnements moites et humides, tels que la terre, les r\u00e9servoirs d\u2019eau, les mat\u00e9riaux ignifug\u00e9s, la literie, les coussins et oreillers, les conduits de ventilation, ainsi que de nombreux autres composants de syst\u00e8mes de CVAC.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Int\u00e9ressons-nous donc un peu plus en d\u00e9tail \u00e0 cette <a href=\"https:\/\/fr.bustmold.com\/ressources\/a-propos-de-la-moisissure\/\">moisissure<\/a>: o\u00f9 peut-on la trouver? Quels d\u00e9g\u00e2ts peut-elle causer? Comment nous en prot\u00e9ger?<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Ou_prolifere_la_moisissure_Aspergillus_Ochraceus\"><\/span>O\u00f9 prolif\u00e8re la moisissure <em>Aspergillus Ochraceus<\/em>?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Bien que la terre soit consid\u00e9r\u00e9e comme \u00e9tant son habitat originel, avec le temps, <a href=\"https:\/\/fr.bustmold.com\/ressources\/a-propos-de-la-moisissure\/causes-de-la-moisissure\/\">cette moisissure a \u00e9t\u00e9 capable de muter pour se d\u00e9velopper dans une large vari\u00e9t\u00e9 d\u2019environnements<\/a>, particuli\u00e8rement lorsqu\u2019ils sont humide. On la retrouve ainsi fr\u00e9quemment sur la nourriture s\u00e8che, notamment les viandes s\u00e9ch\u00e9es, les poissons et de nombreuses esp\u00e8ces de haricots, noix et graines.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour se d\u00e9velopper, une colonie d\u2019<em>A. Ochraceus<\/em> a besoin de temp\u00e9ratures comprises entre 8 et 37\u00b0C, la tranche optimale se situant entre 24 et 31\u00b0C. Elles sont besoin d\u2019un apport en humidit\u00e9 cons\u00e9quent, avec une activit\u00e9 d\u2019eau id\u00e9ale situ\u00e9e entre 0,95 et 0,99 [1].<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le besoin d\u2019humidit\u00e9 est une constante de nombreux <a href=\"https:\/\/fr.bustmold.com\/ressources\/a-propos-de-la-moisissure\/type-de-moisissure\/\">types de moisissures<\/a>, particuli\u00e8rement celles que nous retrouvons le plus dans nos environnements int\u00e9rieurs. Des endroits tels que les <a href=\"https:\/\/fr.bustmold.com\/nos-services\/assainissement\/elimination-des-moisissures\/sous-sol\/\">sous-sols<\/a>, <a href=\"https:\/\/fr.bustmold.com\/nos-services\/assainissement\/elimination-des-moisissures\/grenier\/\">entretoits<\/a>, syst\u00e8mes de ventilation, conduits d\u2019a\u00e9ration, \u00e9tag\u00e8res de stockages, <a href=\"https:\/\/fr.bustmold.com\/nos-services\/assainissement\/elimination-des-moisissures\/salle-de-bain\/\">salles de bains<\/a> et buanderies sont donc les plus \u00e0 risque de voir <a href=\"https:\/\/fr.bustmold.com\/ressources\/a-propos-de-la-moisissure\/ou-se-cache-la-moisissure\/\">de la moisissure se d\u00e9velopper<\/a>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Aspergillus_Ochraceus_et_le_cannabis\"><\/span><em>Aspergillus Ochraceus<\/em> et le cannabis<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Comme de nombreuses familles de moisissures, <em>A. Ochraceus<\/em> se d\u00e9veloppe sur de nombreux v\u00e9g\u00e9taux, notamment le ma\u00efs, le riz ou encore de nombreuses autres familles de fruits et de noix.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les plants de cannabis sont eux aussi affect\u00e9s. La pr\u00e9sence de la moisissure sur ce v\u00e9g\u00e9tal peut devenir probl\u00e9matique. Des \u00e9tudes, en effet, \u00e9tablissent un lien entre la consommation de marijuana et le d\u00e9veloppement de l\u2019aspergillose pulmonaire [2,3,4,5].<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Consommer la marijuana \u00e0 l\u2019aide d\u2019un vaporisateur, plut\u00f4t que de la fumer, peut augmenter les risques d\u2019infections. Une temp\u00e9rature de consommation plus basse, en effet, va permettre aux spores fongiques de survivre.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Quelles_sont_les_especes_connues_dAspergillus_Ochraceus\"><\/span>Quelles sont les esp\u00e8ces connues d\u2019<em>Aspergillus Ochraceus<\/em>?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><em>A. Ochraceus<\/em> a \u00e9t\u00e9 d\u00e9crite pour la premi\u00e8re fois par Karl Adolf Wilhelm en 1877. Par la suite, plusieurs autres esp\u00e8ces similaires ont \u00e9t\u00e9 ajout\u00e9e au \u201cgroupe <em>Aspergillus Ochraceus<\/em>\u201d, notamment <em>A. Alutaceus<\/em> (1875), <em>A. Ochraceus<\/em> <em>var. Microspora<\/em> (1908) et <em>A. Ochraceus<\/em> <em>var. Petaliformis<\/em> (1957).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En 1979, deux nouvelles esp\u00e8ces furent ajout\u00e9es au groupe, <em>Aspergillus Bridgeri<\/em>, d\u00e9couverte dans les sols du Wyoming et <em>Aspergillus Campestris<\/em>, d\u00e9couverte dans le Dakota du Nord.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Aspergillus_Ochraceus_et_votre_sante\"><\/span><em>Aspergillus Ochraceus<\/em> et votre sant\u00e9<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Les spores d\u2019<em>A. Ochraceus<\/em> sont consid\u00e9r\u00e9s comme \u00e9tant des allerg\u00e8nes et des irritants, qui provoquent notamment la pneumopathie d\u2019hypersensibilit\u00e9 et des dermatites. <em>A. Ochraceus<\/em> est aussi connue pour produire plusieurs mycotoxines, notamment des ochratoxines, de l\u2019acide p\u00e9nicillique, des xanthomegnines, des viomellines [1]. Parmi ces substances, l\u2019ochratoxine A est un carcinog\u00e8ne reconnu qui peut provoquer de nombreuses l\u00e9sions r\u00e9nales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les types de maladies provoqu\u00e9es par <em>A. Ochraceus<\/em> varient en s\u00e9v\u00e9rit\u00e9, allant de r\u00e9actions similaires aux allergies jusqu\u2019\u00e0 des infections \u00e0 l\u2019issue potentiellement fatale [8]. \u00c0 ce propos, l\u2019aspergillose est un terme collectif utilis\u00e9 pour d\u00e9signer un groupe de maladies li\u00e9es aux moisissures du genre Aspergillus. Les sympt\u00f4mes de l\u2019aspergillose incluent de la fi\u00e8vre, de la toux, des douleurs \u00e0 la poitrines et des difficult\u00e9s respiratoires.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ces signes \u00e9tant communs \u00e0 de nombreuses autres maladies, il est difficile de diagnostiquer l\u2019aspergillose sans l\u2019aide d\u2019un sp\u00e9cialiste. La s\u00e9v\u00e9rit\u00e9 de la maladie, par ailleurs, va \u00eatre d\u00e9termin\u00e9e par de nombreux facteurs, notamment l\u2019\u00e9tat du syst\u00e8me immunitaire de la personne contamin\u00e9e. La plupart d\u2019entre nous, en effet, inhale des centaines de spores quotidiennement. L\u2019aspergillose, toutefois, n\u2019affectera quasiment jamais des patients en bonne sant\u00e9, vivant dans des conditions normales. Si les concentrations de spores que vous inhalez viennent \u00e0 augmenter, toutefois, vous pouvez alors \u00eatre dans une situation \u00e0 risque.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>A. Ochraceus<\/em> est tr\u00e8s courante en int\u00e9rieur, particuli\u00e8rement en automne et en hiver. Il est donc important pour vous de ne pas attendre pour <a href=\"https:\/\/fr.bustmold.com\/nos-services\/analyses\/analyse-de-moisissure\/\">faire tester votre maison<\/a>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Quelles_allergies_peuvent-elles_etres_provoquees_par_Aspergillus_Ochraceus\"><\/span>Quelles allergies peuvent-elles \u00eatres provoqu\u00e9es par <em>Aspergillus Ochraceus<\/em>?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Comme tous les champignons, cette moisissure se reproduit en rel\u00e2chant des spores qui se dispersent dans les airs pour se d\u00e9poser sur les endroits qui leur seront favorables, avant de se d\u00e9velopper en nouvelles colonies de moisissure.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lorsque nous respirons ces spores, les probl\u00e8mes sur notre sant\u00e9 peuvent alors commencer. Les gens sensibles aux spores fongiques peuvent alors faire face \u00e0 des r\u00e9actions allergiques.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les sympt\u00f4mes d\u2019une r\u00e9action allergique incluent notamment:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Des d\u00e9mangeaisons cutan\u00e9es<\/li><li>Des difficult\u00e9s respiratoires<\/li><li>De la toux<\/li><li>Des d\u00e9mangeaisons oculaires<\/li><li>Un nez qui coule<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Les enfants et les personnes \u00e2g\u00e9es sont particuli\u00e8rement \u00e0 risque, ainsi que les patients souffrant de probl\u00e8mes pulmonaires tels que l\u2019asthme, la mucoviscidose ou la tuberculose.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Quels_sont_les_problemes_de_sante_lies_a_Aspergillus_Ochraceus\"><\/span>Quels sont les probl\u00e8mes de sant\u00e9 li\u00e9s \u00e0 <em>Aspergillus Ochraceus<\/em>?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Inhaler les spores de cette moisissure, particuli\u00e8rement lorsqu\u2019il s\u2019agit de fortes quantit\u00e9s, peut s\u2019av\u00e9rer <a href=\"https:\/\/fr.bustmold.com\/ressources\/a-propos-de-la-moisissure\/effets-de-la-moisissure-sur-la-sante\/\">extr\u00eamement dangereux pour votre sant\u00e9<\/a>. Dans les pires cas, une inhalation excessive de ces spores peut provoquer des l\u00e9sions permanentes, avec, dans certains cas, une issue fatale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Par ailleurs, un lien a \u00e9t\u00e9 \u00e9tabli entre les spores d\u2019<em>Aspergillus Ochraceus<\/em> et le d\u00e9veloppement de l\u2019asthme chez les enfants en bas \u00e2ge [9]. L\u2019aspergillose bronchopulmonaire, une maladie provoqu\u00e9e par le d\u00e9veloppement de spores fongiques dans le syst\u00e8me pulmonaire d\u2019une personne contamin\u00e9e, peut, dans les cas les plus extr\u00eames, \u00eatre mortelle. Toutefois, les personnes fortement immunod\u00e9prim\u00e9es sont les seules \u00e0 \u00eatre en situation de risque.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En plus de ces maladies pulmonaires, des cas de sinusites paranasales ont aussi \u00e9t\u00e9 attribu\u00e9es \u00e0 l\u2019inhalation de spores d\u2019<em>A. Ochraceus<\/em> [8].<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De plus, <em>A. Ochraceus<\/em> produit une mycotoxine connue sous le nom d\u2019ochratoxine A, qui peut provoquer des probl\u00e8mes graves, et mettre potentiellement en danger votre sant\u00e9 si elle est inhal\u00e9e ou ing\u00e9r\u00e9e. <em>A. Ochraceus<\/em> a \u00e9t\u00e9 reconnue comme une source significative d\u2019ochratoxine A; notamment sur le caf\u00e9 [10]. L\u2019ochratoxine A est un composant neurotoxique, canc\u00e9rog\u00e8ne, aux effets immunosuppresseurs. Elle peut \u00eatre \u00e0 l\u2019origine de tumeurs r\u00e9nales, ainsi que de nombreuses autres maladies affectant les reins [6].<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Traiter_et_prevenir_lapparition_dAspergillus_Ochraceus\"><\/span>Traiter et pr\u00e9venir l\u2019apparition d\u2019<em>Aspergillus Ochraceus<\/em>.<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Concernant les menaces que fait peser <em>A. Ochraceus<\/em> sur les cultures agricoles, il existe de nombreux fongicides qui sont efficaces, notamment l\u2019oxychlorure de cuivre, le soufre et le mancoz\u00e8be. Il s\u2019agit cependant de substances dangereuses, leur utilisation exige donc des pr\u00e9cautions et une formation ad\u00e9quates.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous cherchez \u00e0 d\u00e9contaminer votre maison et \u00e0 \u00e9liminer cette moisissure, il est donc fortement recommand\u00e9 de faire appel \u00e0 des professionnels.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il existe en effet un risque d\u2019inhaler des spores dangereuses, en fortes quantit\u00e9s au moment o\u00f9 vous allez tenter d\u2019\u00e9liminer la moisissure, quelle que soit la m\u00e9thode que vous avez choisie.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Par ailleurs, vous ne pourrez pas \u00eatre s\u00fbr d\u2019avoir d\u00e9tect\u00e9 et \u00e9limin\u00e9 toutes les colonies de moisissures qui se seraient d\u00e9velopp\u00e9es chez vous. Vous resterez donc en situation de risque. La moisissure, en effet, peut \u00eatre particuli\u00e8rement persistante et faire rapidement son retour alors qu\u2019elle semblait \u00eatre totalement \u00e9radiqu\u00e9e. Tr\u00e8s souvent, la source de la moisissure n\u2019est pas \u00e9vidente aux premiers abords. Se contenter d\u2019\u00e9liminer les traces visibles de moisissure ne vous permettra pas d\u2019\u00e9viter sa r\u00e9apparition. Les spores, en effet, sont omnipr\u00e9sents dans l\u2019air qui nous entoure, et pourront donc se d\u00e9velopper partout o\u00f9 les conditions leur seront favorables.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/fr.bustmold.com\/contactez-nous\/\">En faisant appel aux professionnels de Mold Busters<\/a>, vous aurez l\u2019assurance d\u2019<a href=\"https:\/\/fr.bustmold.com\/nos-services\/assainissement\/elimination-des-moisissures\/\">\u00e9liminer toute les moisissures<\/a> de votre maison, quel que soit l\u2019endroit o\u00f9 elle se d\u00e9veloppe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous m\u00e8nerons ce travail de mani\u00e8re s\u00e9curitaire et efficace, tout en pouvant vous fournir de pr\u00e9cieux conseils sur les pratiques \u00e0 suivre pour vous assurer que la moisissure ne se r\u00e9installe pas dans votre maison.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il est toujours plus facile de <a href=\"https:\/\/fr.bustmold.com\/ressources\/a-propos-de-la-moisissure\/la-prevention-de-la-moisissure\/\">pr\u00e9venir un probl\u00e8me de moisissure<\/a> que de le traiter. Faire inspecter et tester votre maison de mani\u00e8re proactive et d\u00e9taill\u00e9e, m\u00eame si vous ne savez pas avec pr\u00e9cision si vous avez affaire \u00e0 de la moisissure, est donc fortement conseill\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour vous assurer de vivre dans une maison saine, sans moisissures, <a href=\"https:\/\/fr.bustmold.com\/nos-services\/inspections\/inspection-de-moisissure\/\">contactez d\u00e8s maintenant les professionnels Mold Busters pour une inspection<\/a>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Sources\"><\/span>Sources<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<ol class=\"wp-block-list\"><li>Pitt JI, Hocking AD (2009). <em>Aspergillus<\/em> and Related Teleomorphs. In: Fungi and Food Spoilage. Springer, Boston, MA, pp 470-471<\/li><li>Remington TL, Fuller J, Chiu I (2015). Chronic necrotizing pulmonary aspergillosis in a patient with diabetes and marijuana use. CMAJ. 187(17):1305-8.<\/li><li>Kurup VP, Resnick A, Kagen SL, et al (1983). Allergenic fungi and actinomycetes in smoking materials and their health implications. Mycopathologia 82:61\u20134.<\/li><li>Vaschetto R, Kroumova V, Olivieri C, et al (2012). Early diagnosis of invasive pulmonary aspergillosis in a young immunocompetent patient. New Microbiol 35:77\u201382.<\/li><li>Bal A, Agarwal AN, Das A, et al (2010). Chronic necrotising pulmonary aspergillosis in a marijuana addict: a new cause of amyloidosis. Pathology 42:197\u2013200.<\/li><li>Bui-Klimke TR, Wu F (2015). Ochratoxin A and human health risk: a review of the evidence. Crit Rev Food Sci Nutr. 55(13):1860-9.<\/li><li>Palma N, Cinelli S, Sapora O, Wilson SH, Dogliotti E (2007). Ochratoxin A-induced mutagenesis in mammalian cells is consistent with the production of oxidative stress. Chem Res Toxicol. 20(7):1031-7.<\/li><li>Howard DH (2003). Pathogenic Fungi in Humans and Animals. Marcel Dekker, New York. pp 294-295.<\/li><li>Reponen T, Lockey J, Bernstein DI, et al (2012). Infant origins of childhood asthma associated with specific molds. J Allergy Clin Immunol. 130(3):639-644.e5.<\/li><li>Taniwaki MH, Pitt JI, Teixeira AA, Iamanaka BT (2003). The source of ochratoxin A in Brazilian coffee and its formation in relation to processing methods. Int J Food Microbiol. 82: 173\u2013179.<\/li><\/ol>\n\n\n\n<div class=\"wp-block-uagb-columns uagb-columns__wrap uagb-columns__background-color uagb-columns__stack-none uagb-columns__valign-center uagb-columns__gap-20 align uagb-block-5b67cdaf uagb-columns__columns-2 uagb-columns__max_width-theme\"><div class=\"uagb-columns__overlay\"><\/div><div class=\"uagb-columns__inner-wrap uagb-columns__columns-2\">\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-7f63cba9\"><div class=\"uagb-column__overlay\"><\/div>\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/www.bustmold.com\/wp-content\/uploads\/2023\/01\/mold-removal-guidelines-03-199x300.jpg\" alt=\"mold removal guidelines book cover 199\" class=\"wp-image-1588\"\/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-f3761127\"><div class=\"uagb-column__overlay\"><\/div>\n<p class=\"has-text-align-center has-ast-global-color-5-color has-text-color has-medium-font-size wp-block-paragraph\"><strong>Get Special Gift: <strong>Industry-Standard Mold Removal Guidelines<\/strong><\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-ast-global-color-0-color has-css-opacity has-ast-global-color-0-background-color has-background aligncenter\"\/>\n\n\n\n<p class=\"has-text-align-center has-ast-global-color-5-color has-text-color wp-block-paragraph\">Download the <strong>industry-standard guidelines<\/strong> that Mold Busters use in their own mold removal services, including news, tips and special offers:<\/p>\n\n\n<script type=\"text\/javascript\">var gform;gform||(document.addEventListener(\"gform_main_scripts_loaded\",function(){gform.scriptsLoaded=!0}),window.addEventListener(\"DOMContentLoaded\",function(){gform.domLoaded=!0}),gform={domLoaded:!1,scriptsLoaded:!1,initializeOnLoaded:function(o){gform.domLoaded&&gform.scriptsLoaded?o():!gform.domLoaded&&gform.scriptsLoaded?window.addEventListener(\"DOMContentLoaded\",o):document.addEventListener(\"gform_main_scripts_loaded\",o)},hooks:{action:{},filter:{}},addAction:function(o,n,r,t){gform.addHook(\"action\",o,n,r,t)},addFilter:function(o,n,r,t){gform.addHook(\"filter\",o,n,r,t)},doAction:function(o){gform.doHook(\"action\",o,arguments)},applyFilters:function(o){return gform.doHook(\"filter\",o,arguments)},removeAction:function(o,n){gform.removeHook(\"action\",o,n)},removeFilter:function(o,n,r){gform.removeHook(\"filter\",o,n,r)},addHook:function(o,n,r,t,i){null==gform.hooks[o][n]&&(gform.hooks[o][n]=[]);var e=gform.hooks[o][n];null==i&&(i=n+\"_\"+e.length),gform.hooks[o][n].push({tag:i,callable:r,priority:t=null==t?10:t})},doHook:function(n,o,r){var t;if(r=Array.prototype.slice.call(r,1),null!=gform.hooks[n][o]&&((o=gform.hooks[n][o]).sort(function(o,n){return o.priority-n.priority}),o.forEach(function(o){\"function\"!=typeof(t=o.callable)&&(t=window[t]),\"action\"==n?t.apply(null,r):r[0]=t.apply(null,r)})),\"filter\"==n)return r[0]},removeHook:function(o,n,t,i){var r;null!=gform.hooks[o][n]&&(r=(r=gform.hooks[o][n]).filter(function(o,n,r){return!!(null!=i&&i!=o.tag||null!=t&&t!=o.priority)}),gform.hooks[o][n]=r)}});<\/script>\n                <div class='gf_browser_gecko gform_wrapper gravity-theme gform-theme--no-framework' data-form-theme='gravity-theme' data-form-index='0' id='gform_wrapper_1' ><style>#gform_wrapper_1[data-form-index=\"0\"].gform-theme,[data-parent-form=\"1_0\"]{--gf-color-primary: #204ce5;--gf-color-primary-rgb: 32, 76, 229;--gf-color-primary-contrast: #fff;--gf-color-primary-contrast-rgb: 255, 255, 255;--gf-color-primary-darker: #001AB3;--gf-color-primary-lighter: #527EFF;--gf-color-secondary: #fff;--gf-color-secondary-rgb: 255, 255, 255;--gf-color-secondary-contrast: #112337;--gf-color-secondary-contrast-rgb: 17, 35, 55;--gf-color-secondary-darker: #F5F5F5;--gf-color-secondary-lighter: #FFFFFF;--gf-color-out-ctrl-light: rgba(17, 35, 55, 0.1);--gf-color-out-ctrl-light-rgb: 17, 35, 55;--gf-color-out-ctrl-light-darker: rgba(104, 110, 119, 0.35);--gf-color-out-ctrl-light-lighter: #F5F5F5;--gf-color-out-ctrl-dark: #585e6a;--gf-color-out-ctrl-dark-rgb: 88, 94, 106;--gf-color-out-ctrl-dark-darker: #112337;--gf-color-out-ctrl-dark-lighter: rgba(17, 35, 55, 0.65);--gf-color-in-ctrl: #fff;--gf-color-in-ctrl-rgb: 255, 255, 255;--gf-color-in-ctrl-contrast: #112337;--gf-color-in-ctrl-contrast-rgb: 17, 35, 55;--gf-color-in-ctrl-darker: #F5F5F5;--gf-color-in-ctrl-lighter: #FFFFFF;--gf-color-in-ctrl-primary: #204ce5;--gf-color-in-ctrl-primary-rgb: 32, 76, 229;--gf-color-in-ctrl-primary-contrast: #fff;--gf-color-in-ctrl-primary-contrast-rgb: 255, 255, 255;--gf-color-in-ctrl-primary-darker: #001AB3;--gf-color-in-ctrl-primary-lighter: #527EFF;--gf-color-in-ctrl-light: rgba(17, 35, 55, 0.1);--gf-color-in-ctrl-light-rgb: 17, 35, 55;--gf-color-in-ctrl-light-darker: rgba(104, 110, 119, 0.35);--gf-color-in-ctrl-light-lighter: #F5F5F5;--gf-color-in-ctrl-dark: #585e6a;--gf-color-in-ctrl-dark-rgb: 88, 94, 106;--gf-color-in-ctrl-dark-darker: #112337;--gf-color-in-ctrl-dark-lighter: rgba(17, 35, 55, 0.65);--gf-radius: 3px;--gf-font-size-secondary: 14px;--gf-font-size-tertiary: 13px;--gf-icon-ctrl-number: url(\"data:image\/svg+xml,%3Csvg width='8' height='14' viewBox='0 0 8 14' fill='none' xmlns='http:\/\/www.w3.org\/2000\/svg'%3E%3Cpath fill-rule='evenodd' clip-rule='evenodd' d='M4 0C4.26522 5.96046e-08 4.51957 0.105357 4.70711 0.292893L7.70711 3.29289C8.09763 3.68342 8.09763 4.31658 7.70711 4.70711C7.31658 5.09763 6.68342 5.09763 6.29289 4.70711L4 2.41421L1.70711 4.70711C1.31658 5.09763 0.683417 5.09763 0.292893 4.70711C-0.0976311 4.31658 -0.097631 3.68342 0.292893 3.29289L3.29289 0.292893C3.48043 0.105357 3.73478 0 4 0ZM0.292893 9.29289C0.683417 8.90237 1.31658 8.90237 1.70711 9.29289L4 11.5858L6.29289 9.29289C6.68342 8.90237 7.31658 8.90237 7.70711 9.29289C8.09763 9.68342 8.09763 10.3166 7.70711 10.7071L4.70711 13.7071C4.31658 14.0976 3.68342 14.0976 3.29289 13.7071L0.292893 10.7071C-0.0976311 10.3166 -0.0976311 9.68342 0.292893 9.29289Z' fill='rgba(17, 35, 55, 0.65)'\/%3E%3C\/svg%3E\");--gf-icon-ctrl-select: url(\"data:image\/svg+xml,%3Csvg width='10' height='6' viewBox='0 0 10 6' fill='none' xmlns='http:\/\/www.w3.org\/2000\/svg'%3E%3Cpath fill-rule='evenodd' clip-rule='evenodd' d='M0.292893 0.292893C0.683417 -0.097631 1.31658 -0.097631 1.70711 0.292893L5 3.58579L8.29289 0.292893C8.68342 -0.0976311 9.31658 -0.0976311 9.70711 0.292893C10.0976 0.683417 10.0976 1.31658 9.70711 1.70711L5.70711 5.70711C5.31658 6.09763 4.68342 6.09763 4.29289 5.70711L0.292893 1.70711C-0.0976311 1.31658 -0.0976311 0.683418 0.292893 0.292893Z' fill='rgba(17, 35, 55, 0.65)'\/%3E%3C\/svg%3E\");--gf-icon-ctrl-search: url(\"data:image\/svg+xml,%3Csvg version='1.1' xmlns='http:\/\/www.w3.org\/2000\/svg' width='640' height='640'%3E%3Cpath d='M256 128c-70.692 0-128 57.308-128 128 0 70.691 57.308 128 128 128 70.691 0 128-57.309 128-128 0-70.692-57.309-128-128-128zM64 256c0-106.039 85.961-192 192-192s192 85.961 192 192c0 41.466-13.146 79.863-35.498 111.248l154.125 154.125c12.496 12.496 12.496 32.758 0 45.254s-32.758 12.496-45.254 0L367.248 412.502C335.862 434.854 297.467 448 256 448c-106.039 0-192-85.962-192-192z' fill='rgba(17, 35, 55, 0.65)'\/%3E%3C\/svg%3E\");--gf-label-space-y-secondary: var(--gf-label-space-y-md-secondary);--gf-ctrl-border-color: #686e77;--gf-ctrl-size: var(--gf-ctrl-size-md);--gf-ctrl-label-color-primary: #112337;--gf-ctrl-label-color-secondary: #112337;--gf-ctrl-choice-size: var(--gf-ctrl-choice-size-md);--gf-ctrl-checkbox-check-size: var(--gf-ctrl-checkbox-check-size-md);--gf-ctrl-radio-check-size: var(--gf-ctrl-radio-check-size-md);--gf-ctrl-btn-font-size: var(--gf-ctrl-btn-font-size-md);--gf-ctrl-btn-padding-x: var(--gf-ctrl-btn-padding-x-md);--gf-ctrl-btn-size: var(--gf-ctrl-btn-size-md);--gf-ctrl-btn-border-color-secondary: #686e77;--gf-ctrl-file-btn-bg-color-hover: #EBEBEB;--gf-field-pg-steps-number-color: rgba(17, 35, 55, 0.8);}<\/style><div id='gf_1' class='gform_anchor' tabindex='-1'><\/div><form method='post' enctype='multipart\/form-data' target='gform_ajax_frame_1' id='gform_1'  action='\/fr\/wp-json\/wp\/v2\/pages\/293#gf_1' data-formid='1' novalidate>\n                        <div class='gform-body gform_body'><div id='gform_fields_1' class='gform_fields top_label form_sublabel_below description_below'><fieldset id=\"field_1_1\" class=\"gfield gfield--type-name gfield--width-half gfield_contains_required field_sublabel_hidden_label gfield--no-description field_description_below hidden_label gfield_visibility_visible\"  data-js-reload=\"field_1_1\" ><legend class='gfield_label gform-field-label gfield_label_before_complex' >Name<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_text\">(N\u00e9cessaire)<\/span><\/span><\/legend><div class='ginput_complex ginput_container ginput_container--name no_prefix has_first_name no_middle_name no_last_name no_suffix gf_name_has_1 ginput_container_name gform-grid-row' id='input_1_1'>\n                            \n                            <span id='input_1_1_3_container' class='name_first gform-grid-col gform-grid-col--size-auto' >\n                                                    <input type='text' name='input_1.3' id='input_1_1_3' value=''   aria-required='true'   placeholder='Your Name'  \/>\n                                                    <label for='input_1_1_3' class='gform-field-label gform-field-label--type-sub hidden_sub_label screen-reader-text'>Pr\u00e9nom<\/label>\n                                                <\/span>\n                            \n                            \n                            \n                        <\/div><\/fieldset><div id=\"field_1_2\" class=\"gfield gfield--type-email gfield--width-half field_sublabel_below gfield--no-description field_description_below hidden_label gfield_visibility_visible\"  data-js-reload=\"field_1_2\" ><label class='gfield_label gform-field-label' for='input_1_2'>Email<\/label><div class='ginput_container ginput_container_email'>\n                            <input name='input_2' id='input_1_2' type='email' value='' class='large'   placeholder='Your E-mail'  aria-invalid=\"false\"  \/>\n                        <\/div><\/div><\/div><\/div>\n        <div class='gform_footer top_label'> <input type='submit' id='gform_submit_button_1' class='gform_button button' value='Sign Up!'  onclick='if(window[\"gf_submitting_1\"]){return false;}  if( !jQuery(\"#gform_1\")[0].checkValidity || jQuery(\"#gform_1\")[0].checkValidity()){window[\"gf_submitting_1\"]=true;}  ' onkeypress='if( event.keyCode == 13 ){ if(window[\"gf_submitting_1\"]){return false;} if( !jQuery(\"#gform_1\")[0].checkValidity || jQuery(\"#gform_1\")[0].checkValidity()){window[\"gf_submitting_1\"]=true;}  jQuery(\"#gform_1\").trigger(\"submit\",[true]); }' \/> <input type='hidden' name='gform_ajax' value='form_id=1&amp;title=&amp;description=&amp;tabindex=0&amp;theme=data-form-theme=&#039;gravity-theme&#039;' \/>\n            <input type='hidden' class='gform_hidden' name='is_submit_1' value='1' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submit' value='1' \/>\n            \n            <input type='hidden' class='gform_hidden' name='gform_unique_id' value='' \/>\n            <input type='hidden' class='gform_hidden' name='state_1' value='WyJbXSIsIjBkMTA0NThmNTBiMGU1ZmYxMDhhMmFmMjM3YjhlZjFkIl0=' \/>\n            <input type='hidden' class='gform_hidden' name='gform_target_page_number_1' id='gform_target_page_number_1' value='0' \/>\n            <input type='hidden' class='gform_hidden' name='gform_source_page_number_1' id='gform_source_page_number_1' value='1' \/>\n            <input type='hidden' name='gform_field_values' value='' \/>\n            \n        <\/div>\n                        <p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"ak_\"><label>&#916;<textarea name=\"ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"ak_js\" value=\"158\"\/><script>document.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );<\/script><\/p><\/form>\n                        <\/div>\n\t\t                <iframe style='display:none;width:0px;height:0px;' src='about:blank' name='gform_ajax_frame_1' id='gform_ajax_frame_1' title='Cette iframe contient la logique n\u00e9cessaire pour manipuler Gravity Forms avec Ajax.'><\/iframe>\n\t\t                <script>\ngform.initializeOnLoaded( function() {gformInitSpinner( 1, 'https:\/\/library.bustmold.com\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery('#gform_ajax_frame_1').on('load',function(){var contents = jQuery(this).contents().find('*').html();var is_postback = contents.indexOf('GF_AJAX_POSTBACK') >= 0;if(!is_postback){return;}var form_content = jQuery(this).contents().find('#gform_wrapper_1');var is_confirmation = jQuery(this).contents().find('#gform_confirmation_wrapper_1').length > 0;var is_redirect = contents.indexOf('gformRedirect(){') >= 0;var is_form = form_content.length > 0 && ! is_redirect && ! is_confirmation;var mt = parseInt(jQuery('html').css('margin-top'), 10) + parseInt(jQuery('body').css('margin-top'), 10) + 100;if(is_form){jQuery('#gform_wrapper_1').html(form_content.html());if(form_content.hasClass('gform_validation_error')){jQuery('#gform_wrapper_1').addClass('gform_validation_error');} else {jQuery('#gform_wrapper_1').removeClass('gform_validation_error');}setTimeout( function() { \/* delay the scroll by 50 milliseconds to fix a bug in chrome *\/ jQuery(document).scrollTop(jQuery('#gform_wrapper_1').offset().top - mt); }, 50 );if(window['gformInitDatepicker']) {gformInitDatepicker();}if(window['gformInitPriceFields']) {gformInitPriceFields();}var current_page = jQuery('#gform_source_page_number_1').val();gformInitSpinner( 1, 'https:\/\/library.bustmold.com\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery(document).trigger('gform_page_loaded', [1, current_page]);window['gf_submitting_1'] = false;}else if(!is_redirect){var confirmation_content = jQuery(this).contents().find('.GF_AJAX_POSTBACK').html();if(!confirmation_content){confirmation_content = contents;}setTimeout(function(){jQuery('#gform_wrapper_1').replaceWith(confirmation_content);jQuery(document).scrollTop(jQuery('#gf_1').offset().top - mt);jQuery(document).trigger('gform_confirmation_loaded', [1]);window['gf_submitting_1'] = false;wp.a11y.speak(jQuery('#gform_confirmation_message_1').text());}, 50);}else{jQuery('#gform_1').append(contents);if(window['gformRedirect']) {gformRedirect();}}jQuery(document).trigger('gform_post_render', [1, current_page]);gform.utils.trigger({ event: 'gform\/postRender', native: false, data: { formId: 1, currentPage: current_page } });} );} );\n<\/script>\n<\/div>\n<\/div><\/div>\n\n<hr class=\"wp-block-separator has-text-color has-luminous-vivid-orange-color has-css-opacity has-luminous-vivid-orange-background-color has-background aligncenter\"\/>\n\n<section class=\"wp-block-uagb-columns uagb-columns__wrap uagb-columns__background-none uagb-columns__stack-mobile uagb-columns__valign-center uagb-columns__gap-10 align uagb-block-ee9510ba uagb-columns__columns-4 uagb-columns__max_width-theme\"><div class=\"uagb-columns__overlay\"><\/div><div class=\"uagb-columns__inner-wrap uagb-columns__columns-4\">\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-bfa5bb58\"><div class=\"uagb-column__overlay\"><\/div>\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/www.bustmold.com\/wp-content\/uploads\/2023\/09\/John-Ward.jpg\" alt=\"\" style=\"width:150px;height:150px\"\/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-386b1178\"><div class=\"uagb-column__overlay\"><\/div>\n<p class=\"has-text-align-center wp-block-paragraph\"><strong>Written by:<\/strong><br\/><a href=\"https:\/\/www.bustmold.com\/about-us\/our-team\/john-ward\/\">John Ward<\/a><br\/>Account Executive<br\/>Mold Busters<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-ba032752\"><div class=\"uagb-column__overlay\"><\/div>\n<p class=\"has-text-align-center wp-block-paragraph\"><strong>Fact checked by:<\/strong><br\/><a href=\"https:\/\/www.bustmold.com\/about-us\/our-team\/\">Michael Golubev<\/a><br\/>General Manager<br\/>Mold Busters<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-576699a5\"><div class=\"uagb-column__overlay\"><\/div>\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/www.bustmold.com\/wp-content\/uploads\/2023\/09\/michael-g.jpg\" alt=\"\" style=\"width:150px;height:150px\"\/><\/figure>\n<\/div>\n<\/div><\/section>\n","protected":false},"excerpt":{"rendered":"<p>En tant que membre du genre Aspergillus (qui regroupe environ 200 esp\u00e8ces de champignons dans le monde), Aspergillus Ochraceus est une esp\u00e8ce de moisissure que l\u2019on rencontre le plus souvent dans la terre, sur le grains ainsi que sur les aliments secs. Ce type de moisissure produit une mycotoxine, l\u2019ochratoxine A (OTA) qui est assez &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/library.bustmold.com\/fr\/aspergillus\/aspergillus-ochraceus\/\"> <span class=\"screen-reader-text\">Aspergillus ochraceus<\/span> Lire la suite \u00bb<\/a><\/p>\n","protected":false},"author":1,"featured_media":296,"parent":209,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"_uag_custom_page_level_css":"","site-sidebar-layout":"","site-content-layout":"","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","footnotes":""},"tags":[],"class_list":["post-293","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Aspergillus ochraceus: tout savoir sur ses dangers &amp; comment l&#039;\u00e9liminer<\/title>\n<meta name=\"description\" content=\"Aspergillus ochraceus est une moisissure qui peut provoquer de nombreux d\u00e9g\u00e2ts et vous mettre en danger. D\u00e9couvrez comment la pr\u00e9venir et comment la traiter\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/library.bustmold.com\/fr\/aspergillus\/aspergillus-ochraceus\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aspergillus ochraceus: tout savoir sur ses dangers &amp; comment l&#039;\u00e9liminer\" \/>\n<meta property=\"og:description\" content=\"Aspergillus ochraceus est une moisissure qui peut provoquer de nombreux d\u00e9g\u00e2ts et vous mettre en danger. D\u00e9couvrez comment la pr\u00e9venir et comment la traiter\" \/>\n<meta property=\"og:url\" content=\"https:\/\/library.bustmold.com\/fr\/aspergillus\/aspergillus-ochraceus\/\" \/>\n<meta property=\"og:site_name\" content=\"Mold Library\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-31T13:19:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bustmold.com\/wp-content\/uploads\/2018\/09\/aspergillus-ochraceus.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.bustmold.com\/wp-content\/uploads\/2018\/09\/aspergillus-ochraceus.jpg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/library.bustmold.com\/fr\/aspergillus\/aspergillus-ochraceus\/\",\"url\":\"https:\/\/library.bustmold.com\/fr\/aspergillus\/aspergillus-ochraceus\/\",\"name\":\"Aspergillus ochraceus: tout savoir sur ses dangers & comment l'\u00e9liminer\",\"isPartOf\":{\"@id\":\"https:\/\/library.bustmold.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/library.bustmold.com\/fr\/aspergillus\/aspergillus-ochraceus\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/library.bustmold.com\/fr\/aspergillus\/aspergillus-ochraceus\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i2.wp.com\/www.bustmold.com\/wp-content\/uploads\/2018\/09\/aspergillus-ochraceus.jpg?w=1200&resize=1200,630&ssl=1\",\"datePublished\":\"2022-05-12T15:37:04+00:00\",\"dateModified\":\"2022-05-31T13:19:25+00:00\",\"description\":\"Aspergillus ochraceus est une moisissure qui peut provoquer de nombreux d\u00e9g\u00e2ts et vous mettre en danger. D\u00e9couvrez comment la pr\u00e9venir et comment la traiter\",\"breadcrumb\":{\"@id\":\"https:\/\/library.bustmold.com\/fr\/aspergillus\/aspergillus-ochraceus\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/library.bustmold.com\/fr\/aspergillus\/aspergillus-ochraceus\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/library.bustmold.com\/fr\/aspergillus\/aspergillus-ochraceus\/#primaryimage\",\"url\":\"https:\/\/i2.wp.com\/www.bustmold.com\/wp-content\/uploads\/2018\/09\/aspergillus-ochraceus.jpg?w=1200&resize=1200,630&ssl=1\",\"contentUrl\":\"https:\/\/i2.wp.com\/www.bustmold.com\/wp-content\/uploads\/2018\/09\/aspergillus-ochraceus.jpg?w=1200&resize=1200,630&ssl=1\",\"width\":\"1200\",\"height\":\"630\",\"caption\":\"Aspergillus ochraceus\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/library.bustmold.com\/fr\/aspergillus\/aspergillus-ochraceus\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Mold Library\",\"item\":\"https:\/\/library.bustmold.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aspergillus\",\"item\":\"https:\/\/library.bustmold.com\/fr\/aspergillus\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Aspergillus ochraceus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/library.bustmold.com\/fr\/#website\",\"url\":\"https:\/\/library.bustmold.com\/fr\/\",\"name\":\"Mold Library\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/library.bustmold.com\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/library.bustmold.com\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/library.bustmold.com\/fr\/#organization\",\"name\":\"Mold Busters\",\"url\":\"https:\/\/library.bustmold.com\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/library.bustmold.com\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/library.bustmold.com\/wp-content\/uploads\/2022\/05\/mold-busters-logo.svg\",\"contentUrl\":\"https:\/\/library.bustmold.com\/wp-content\/uploads\/2022\/05\/mold-busters-logo.svg\",\"width\":794,\"height\":313,\"caption\":\"Mold Busters\"},\"image\":{\"@id\":\"https:\/\/library.bustmold.com\/fr\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aspergillus ochraceus: tout savoir sur ses dangers & comment l'\u00e9liminer","description":"Aspergillus ochraceus est une moisissure qui peut provoquer de nombreux d\u00e9g\u00e2ts et vous mettre en danger. D\u00e9couvrez comment la pr\u00e9venir et comment la traiter","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/library.bustmold.com\/fr\/aspergillus\/aspergillus-ochraceus\/","og_locale":"fr_FR","og_type":"article","og_title":"Aspergillus ochraceus: tout savoir sur ses dangers & comment l'\u00e9liminer","og_description":"Aspergillus ochraceus est une moisissure qui peut provoquer de nombreux d\u00e9g\u00e2ts et vous mettre en danger. D\u00e9couvrez comment la pr\u00e9venir et comment la traiter","og_url":"https:\/\/library.bustmold.com\/fr\/aspergillus\/aspergillus-ochraceus\/","og_site_name":"Mold Library","article_modified_time":"2022-05-31T13:19:25+00:00","og_image":[{"url":"https:\/\/www.bustmold.com\/wp-content\/uploads\/2018\/09\/aspergillus-ochraceus.jpg"}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/www.bustmold.com\/wp-content\/uploads\/2018\/09\/aspergillus-ochraceus.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/library.bustmold.com\/fr\/aspergillus\/aspergillus-ochraceus\/","url":"https:\/\/library.bustmold.com\/fr\/aspergillus\/aspergillus-ochraceus\/","name":"Aspergillus ochraceus: tout savoir sur ses dangers & comment l'\u00e9liminer","isPartOf":{"@id":"https:\/\/library.bustmold.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/library.bustmold.com\/fr\/aspergillus\/aspergillus-ochraceus\/#primaryimage"},"image":{"@id":"https:\/\/library.bustmold.com\/fr\/aspergillus\/aspergillus-ochraceus\/#primaryimage"},"thumbnailUrl":"https:\/\/i2.wp.com\/www.bustmold.com\/wp-content\/uploads\/2018\/09\/aspergillus-ochraceus.jpg?w=1200&resize=1200,630&ssl=1","datePublished":"2022-05-12T15:37:04+00:00","dateModified":"2022-05-31T13:19:25+00:00","description":"Aspergillus ochraceus est une moisissure qui peut provoquer de nombreux d\u00e9g\u00e2ts et vous mettre en danger. D\u00e9couvrez comment la pr\u00e9venir et comment la traiter","breadcrumb":{"@id":"https:\/\/library.bustmold.com\/fr\/aspergillus\/aspergillus-ochraceus\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/library.bustmold.com\/fr\/aspergillus\/aspergillus-ochraceus\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/library.bustmold.com\/fr\/aspergillus\/aspergillus-ochraceus\/#primaryimage","url":"https:\/\/i2.wp.com\/www.bustmold.com\/wp-content\/uploads\/2018\/09\/aspergillus-ochraceus.jpg?w=1200&resize=1200,630&ssl=1","contentUrl":"https:\/\/i2.wp.com\/www.bustmold.com\/wp-content\/uploads\/2018\/09\/aspergillus-ochraceus.jpg?w=1200&resize=1200,630&ssl=1","width":"1200","height":"630","caption":"Aspergillus ochraceus"},{"@type":"BreadcrumbList","@id":"https:\/\/library.bustmold.com\/fr\/aspergillus\/aspergillus-ochraceus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Mold Library","item":"https:\/\/library.bustmold.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Aspergillus","item":"https:\/\/library.bustmold.com\/fr\/aspergillus\/"},{"@type":"ListItem","position":3,"name":"Aspergillus ochraceus"}]},{"@type":"WebSite","@id":"https:\/\/library.bustmold.com\/fr\/#website","url":"https:\/\/library.bustmold.com\/fr\/","name":"Mold Library","description":"","publisher":{"@id":"https:\/\/library.bustmold.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/library.bustmold.com\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/library.bustmold.com\/fr\/#organization","name":"Mold Busters","url":"https:\/\/library.bustmold.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/library.bustmold.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/library.bustmold.com\/wp-content\/uploads\/2022\/05\/mold-busters-logo.svg","contentUrl":"https:\/\/library.bustmold.com\/wp-content\/uploads\/2022\/05\/mold-busters-logo.svg","width":794,"height":313,"caption":"Mold Busters"},"image":{"@id":"https:\/\/library.bustmold.com\/fr\/#\/schema\/logo\/image\/"}}]}},"uagb_featured_image_src":{"full":["https:\/\/i2.wp.com\/www.bustmold.com\/wp-content\/uploads\/2018\/09\/aspergillus-ochraceus.jpg?w=1200&resize=1200,630&ssl=1",1200,630,false],"thumbnail":["https:\/\/i2.wp.com\/www.bustmold.com\/wp-content\/uploads\/2018\/09\/aspergillus-ochraceus.jpg?w=150&resize=150,150&ssl=1",150,150,false],"medium":["https:\/\/i2.wp.com\/www.bustmold.com\/wp-content\/uploads\/2018\/09\/aspergillus-ochraceus.jpg?w=300&resize=300,300&ssl=1",300,300,false],"medium_large":["https:\/\/i2.wp.com\/www.bustmold.com\/wp-content\/uploads\/2018\/09\/aspergillus-ochraceus.jpg?w=768&resize=768,0&ssl=1",768,0,false],"large":["https:\/\/i2.wp.com\/www.bustmold.com\/wp-content\/uploads\/2018\/09\/aspergillus-ochraceus.jpg?w=1024&resize=1024,1024&ssl=1",1024,1024,false],"1536x1536":["https:\/\/i2.wp.com\/www.bustmold.com\/wp-content\/uploads\/2018\/09\/aspergillus-ochraceus.jpg?w=1536&resize=1536,1536&ssl=1",1536,1536,false],"2048x2048":["https:\/\/i2.wp.com\/www.bustmold.com\/wp-content\/uploads\/2018\/09\/aspergillus-ochraceus.jpg?w=2048&resize=2048,2048&ssl=1",2048,2048,false]},"uagb_author_info":{"display_name":"mblibrary","author_link":"https:\/\/library.bustmold.com\/fr\/author\/mblibrary\/"},"uagb_comment_info":0,"uagb_excerpt":"En tant que membre du genre Aspergillus (qui regroupe environ 200 esp\u00e8ces de champignons dans le monde), Aspergillus Ochraceus est une esp\u00e8ce de moisissure que l\u2019on rencontre le plus souvent dans la terre, sur le grains ainsi que sur les aliments secs. Ce type de moisissure produit une mycotoxine, l\u2019ochratoxine A (OTA) qui est assez\u2026","_links":{"self":[{"href":"https:\/\/library.bustmold.com\/fr\/wp-json\/wp\/v2\/pages\/293","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/library.bustmold.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/library.bustmold.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/library.bustmold.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/library.bustmold.com\/fr\/wp-json\/wp\/v2\/comments?post=293"}],"version-history":[{"count":2,"href":"https:\/\/library.bustmold.com\/fr\/wp-json\/wp\/v2\/pages\/293\/revisions"}],"predecessor-version":[{"id":1142,"href":"https:\/\/library.bustmold.com\/fr\/wp-json\/wp\/v2\/pages\/293\/revisions\/1142"}],"up":[{"embeddable":true,"href":"https:\/\/library.bustmold.com\/fr\/wp-json\/wp\/v2\/pages\/209"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/library.bustmold.com\/fr\/wp-json\/wp\/v2\/media\/296"}],"wp:attachment":[{"href":"https:\/\/library.bustmold.com\/fr\/wp-json\/wp\/v2\/media?parent=293"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/library.bustmold.com\/fr\/wp-json\/wp\/v2\/tags?post=293"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}