{"id":590,"date":"2022-05-17T13:43:48","date_gmt":"2022-05-17T13:43:48","guid":{"rendered":"https:\/\/library.bustmold.com\/?page_id=590"},"modified":"2023-12-22T15:30:38","modified_gmt":"2023-12-22T15:30:38","slug":"eurotium","status":"publish","type":"page","link":"https:\/\/library.bustmold.com\/fr\/eurotium\/","title":{"rendered":"Eurotium"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La plupart des esp\u00e8ces de champignons ont des cycles de vie compliqu\u00e9s, pl\u00e9omorphes. Cela signifie donc qu\u2019ils peuvent exister sous deux formes, une forme anamorphe, au cours de laquelle il se reproduit asexuellement et produit des copies de lui-m\u00eame g\u00e9n\u00e9tiquement identiques, et une forme t\u00e9l\u00e9omorphe qui appara\u00eet lorsque deux champignons g\u00e9n\u00e9tiquement compatibles fusionnent et produit des appareils sporif\u00e8res. Les formes t\u00e9l\u00e9omorphes se reproduisent sexuellement, ce qui signifie que les g\u00e9nomes de deux champignons se combinent, produisant ainsi un organisme g\u00e9n\u00e9tiquement unique.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Quest-ce_quEurotium\"><\/span>Qu\u2019est-ce qu\u2019<em>Eurotium<\/em>?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Eurotium<\/em> est un genre qui englobe les formes t\u00e9l\u00e9omorphes de plusieurs esp\u00e8ces d\u2019<em>Aspergillus<\/em>, notamment <em>Aspergillus glaucus<\/em>. Toutefois, bien que les formes t\u00e9l\u00e9omoprhes d\u2019<em>Aspergillus<\/em> aient \u00e9t\u00e9 d\u00e9finies en au moins huit genres, <em>Eurotium<\/em> est le plus couramment en contact avec les humains, \u00e9tant donn\u00e9 qu\u2019il provoque fr\u00e9quemment <a href=\"https:\/\/fr.bustmold.com\/ressources\/a-propos-de-la-moisissure\/ou-se-cache-la-moisissure\/la-moisissure-sur-les-aliments\/\">le pourrissement d\u2019aliments<\/a>. 81 esp\u00e8ces ont \u00e9t\u00e9 d\u00e9crites dans ce genre, les plus connues \u00e9tant <em>E. amstelodami, E.chevalieri, E. herbariorum et E. repens<\/em>.<\/p>\n\n\n\n<figure class=\"wp-block-image\" id=\"attachment_20214\"><img decoding=\"async\" src=\"https:\/\/www.bustmold.com\/wp-content\/uploads\/2019\/07\/Eurotium-aspergillus-glaccus.jpg\" alt=\"Eurotium aspergillus glaccus\" class=\"wp-image-20214\"\/><figcaption class=\"wp-element-caption\"><a rel=\"noreferrer noopener\" href=\"https:\/\/commons.wikimedia.org\/wiki\/File:PSM_V09_D432_Eurotium_aspergillus_glaccus.jpg\" target=\"_blank\"><em>Eurotium aspergillus glaccus<\/em><\/a><\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Un_organisme_deux_noms\"><\/span>Un organisme, deux noms?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Oui, cela peut para\u00eetre \u00e9trange et un peu confus aux premiers abords, mais il s\u2019agit d\u2019une situation assez courante dans le monde des champignons, o\u00f9 une forme t\u00e9l\u00e9omorphe et une forme anamorphe d\u2019un m\u00eame organisme peuvent prendre deux noms diff\u00e9rents. Par exemple, la <a href=\"https:\/\/fr.bustmold.com\/ressources\/a-propos-de-la-moisissure\/\">moisissure<\/a> connue sous le nom d\u2019<em>Aspergillus glaucus<\/em> peut arriver \u00e0 maturation et prendre alors le nom d\u2019<em>Eurotium herbarorium<\/em> [3].<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ce concept de double nomenclature a \u00e9t\u00e9 \u00e9tabli en 1910, afin de r\u00e9soudre le probl\u00e8me des champignons au cycle de vie pl\u00e9omorphe [4]. Le probl\u00e8me est plus grand qu\u2019il n\u2019y para\u00eet. De nombreux champignons, en effet, se reproduisent uniquement de mani\u00e8re asexu\u00e9e. Cataloguer les champignons aurait pu \u00eatre bien plus simple s\u2019ils pr\u00e9sentaient tous des formes t\u00e9l\u00e9omorphes et anamorphes, \u00e9tant donn\u00e9 qu\u2019il n\u2019y aurait alors aucun inconnue ni aucune incertitude sur l\u2019existence d\u2019une forme sexuelle. De plus, m\u00eame si un champignon poss\u00e8de une forme sexuelle, elle est la plus souvent rare, ne pouvant \u00eatre observ\u00e9e que sous des conditions sp\u00e9cifiques. Dans de nombreux cas, la forme anamorphe et t\u00e9l\u00e9omorphe d\u2019un champignon \u00e9taient bien connues de la science, mais leur lien ne l\u2019\u00e9tait pas pendant de nombreuses ann\u00e9es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">R\u00e9cemment, le d\u00e9veloppement des m\u00e9thodes d\u2019analyses mol\u00e9culaires ont profond\u00e9ment chang\u00e9 la syst\u00e9matique fongique et rel\u00e9gu\u00e9 au pass\u00e9 le syst\u00e8me de double nomenclature. Concr\u00e8tement, les chercheurs ont adopt\u00e9 en 2011 le principe suivant: \u201cun champignon, un nom\u201d. Cependant, bien que la double nomenclature ne soit pas bas\u00e9e sur un principe d\u2019\u00e9volution, elle reste assez utile dans de nombreux domaines, notamment la pathologie de la plante, la mycologie m\u00e9dicale et la microbiologie alimentaire. Les t\u00e9l\u00e9omorphes, en effet, sont la plupart du temps regroup\u00e9s en fonction de leur morphologie et de leur physiologie. Une telle classification est donc tr\u00e8s utile d\u2019un point de vue pratique.<\/p>\n\n\n\n<figure class=\"wp-block-image\" id=\"attachment_20216\"><img decoding=\"async\" src=\"https:\/\/www.bustmold.com\/wp-content\/uploads\/2019\/07\/eurotium-cristatum.jpg\" alt=\"eurotium cristatum\" class=\"wp-image-20216\"\/><figcaption class=\"wp-element-caption\"><em><a rel=\"noreferrer noopener\" href=\"https:\/\/www.flickr.com\/photos\/chadao\/28198313680\" target=\"_blank\">Eurotium cristatum<\/a><\/em><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Prenons par exemples trois genres t\u00e9l\u00e9phomorphes d\u2019<em>Aspergillus: Eurotium, Neosartorya et Emericella<\/em>. Les esp\u00e8ces d\u2019<em>Eurotium<\/em> sont x\u00e9rophiles, et peuvent se d\u00e9velopper dans \u00e0peu pr\u00e8s tous les milieux aquatiques. Les esp\u00e8ces de <em>Neosartorya<\/em>, elles, ne sont par contre pas x\u00e9rophiles. Ce sont des thermophiles qui peuvent coloniser des v\u00e9g\u00e9taux en d\u00e9composition. Elles ont une r\u00e9sistance \u00e0 la chaleur particuli\u00e8rement \u00e9lev\u00e9e, ce qui leur permet par exemple de s\u2019attaquer \u00e0 des produits pasteuris\u00e9s. Enfin, les esp\u00e8ces d\u2019<em>Emericella<\/em>, elles, ne sont ni x\u00e9rophiles, ni thermophiles. Il s\u2019agit de champignons contenus dans la terre, que l\u2019on peut tr\u00e8s rarement observer dans d\u2019autres milieux.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ainsi, si un champignon est d\u00e9tect\u00e9 et identifi\u00e9 comme appartenant \u00e0 l\u2019esp\u00e8ce <em>Eurotium<\/em> dans le secteur de l\u2019agroalimentaire, les personnes en charge de la pr\u00e9vention sanitaire auront imm\u00e9diatement qu\u2019ils ont affaire \u00e0 un organisme x\u00e9rophile. S\u2019il s\u2019agit en revanche de <em>Neosartorya<\/em>, ils sauront alors que la pasteurisation sera sans effet. De ce fait, regrouper toutes ces formes t\u00e9l\u00e9omorphes sous le seul nom d\u2019<em>Aspergillus<\/em> provoquerait alors une perte d\u2019information. Le syst\u00e8me de double nomenclature est donc encore un sujet de d\u00e9bat dans la communaut\u00e9 des mycologues [4].<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Ou_peut-on_retrouver_Eurotium\"><\/span>O\u00f9 peut-on retrouver <em>Eurotium<\/em>?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Les esp\u00e8ces d\u2019<em>Eurotium<\/em> sont connues pour \u00eatre des colonisateurs osmotol\u00e9rants de substrats secs o\u00f9 \u00e0 faible activit\u00e9 d\u2019eau du fait de leur forte concentration en sucres et sels dissous. Ils ont \u00e9t\u00e9 d\u00e9tect\u00e9s notamment dans les eaux dont la salinit\u00e9 d\u00e9passe 17%. La plupart d\u2019entre eux peuvent se d\u00e9velopper dans des eaux dont l\u2019activit\u00e9 est inf\u00e9rieure \u00e0 0,75, certains ayant m\u00eame \u00e9t\u00e9 d\u00e9tect\u00e9 sous 0,64 [5]. On les retrouve souvent dans l\u2019industrie agroalimentaire, \u00e0 l\u2019origine du pourrissement de nombreux aliments. Ils sont par ailleurs courants dans le secteur des nourritures animales, \u00e9tant donn\u00e9 que du grain mal entrepos\u00e9 peut leur fournir un environnement id\u00e9al.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De plus, il s\u2019agit de colonisateurs majeurs de la poussi\u00e8re dans les environnements int\u00e9rieurs, ainsi que sur les cuirs, les textiles et les livres entrepos\u00e9s dans des climats l\u00e9g\u00e8rement humides. <em>E. herbarorium<\/em> est d\u2019ailleurs le troisi\u00e8me champignon le plus courant identifi\u00e9 dans des \u00e9chantillons de gypse moisi pr\u00e9lev\u00e9 dans du placopl\u00e2tre de b\u00e2timents aux Etats-Unis et au Canada. En Am\u00e9rique du nord, les esp\u00e8ces d\u2019<em>Eurotium<\/em> se retrouvent ainsi fr\u00e9quemment dans l\u2019isolation, le placopl\u00e2tre, le bois composite et les dalles de plafond. On les retrouve aussi, isol\u00e9s, dans les filtres de ventilation, les taps, sur les peintures, les dalles en c\u00e9ramique et sur l\u2019efflorescence de ciment. Du fait de leurs capacit\u00e9s \u00e0 se d\u00e9velopper y compris dans des environnement peu humide, ils sont consid\u00e9r\u00e9s comme \u00e9tant des colonisateurs primaires. Les esp\u00e8ces d\u2019<em>Eurotium<\/em> sont reconnues comme \u00e9tant les membres les plus courants de la famille des <em>Ascomycota<\/em> en environnement int\u00e9rieur, notamment sur les murs, les autres surfaces planes et sur la poussi\u00e8re [7].<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Eurotium_est-il_dangereux\"><\/span><em>Eurotium<\/em> est-il dangereux?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Les effets d\u2019<em>Eurotium<\/em> sur la <a href=\"https:\/\/fr.bustmold.com\/ressources\/a-propos-de-la-moisissure\/effets-de-la-moisissure-sur-la-sante\/\">sant\u00e9<\/a> sont encore assez peu \u00e9tudi\u00e9s, compar\u00e9s par exemple aux effets de leurs homologues du genre <em>Aspergillus<\/em>. Leur r\u00f4le dans des infections oculaires, auriculaires et subcutan\u00e9es, des myc\u00e9tomes, des mycoses bronchopulmonaires a \u00e9t\u00e9 cependant reconnu. Par ailleurs, ils sont la cause confirm\u00e9e d\u2019abc\u00e8s c\u00e9r\u00e9braux sur des patients par ailleurs en bonne sant\u00e9 [3]. Enfin, une pr\u00e9sence \u00e9lev\u00e9e d\u2019<em>Eurotium<\/em> dans des \u00e9coles victimes de d\u00e9g\u00e2ts d\u2019eau a \u00e9t\u00e9 associ\u00e9e \u00e0 une pr\u00e9valence plus importante d\u2019asthme chez les enfants qui les fr\u00e9quentaient [9].<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De nombreux rapport cliniques n\u2019offrent qu\u2019une description taxonomique incompl\u00e8te, et ne mentionnent donc pas si la forme t\u00e9l\u00e9omorphe ou anamorphe est \u00e0 l\u2019origine de l\u2019infection. Toutefois, il est probable qu\u2019un nombre significatif de mycoses opportunistes, particuli\u00e8rement les cas de k\u00e9ratite, soient caus\u00e9s par des esp\u00e8ces d\u2019<em>Eurotium<\/em>, bien que l\u2019implication d\u2019une forme thermotol\u00e9rante d\u2019<em>E. Amstelodami<\/em> soit bien plus probable que les relativement peu communes et moins thermotol\u00e9rantes <em>E. herbariorum\/A. glaucus<\/em> [3].<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il est donc effectivement pertinent de souligner les effets sur la sant\u00e9 de <em>A. glaucus<\/em> et de ses proches, \u00e9tant donn\u00e9 qu\u2019ils ne sont s\u00e9par\u00e9s des esp\u00e8ces d\u2019<em>Eurotium<\/em> que par une seule \u00e9tape dans leur cycle de vie. <em>A. glaucus<\/em> a \u00e9t\u00e9 principalement associ\u00e9 \u00e0 une vari\u00e9t\u00e9 d\u2019infections oculaires, particuli\u00e8rement apr\u00e8s une blessure traumatique. D\u2019autres infections sont aussi associ\u00e9es \u00e0 <em>A. glaucus<\/em>, notamment c\u00e9r\u00e9brales, orofaciales, cardiovasculaires, pulmonaires, nasales et auriculaires, bien qu\u2019elles soient rares. Un seul cas fatal, en effet, est associ\u00e9 \u00e0 <em>A. glaucus<\/em>: un patient par ailleurs en bonne sant\u00e9 et immunocomp\u00e9tent est en effet d\u00e9c\u00e9d\u00e9 suite \u00e0 une infection c\u00e9r\u00e9brale caus\u00e9e par <em>A. glaucus<\/em>, qui s\u2019est av\u00e9r\u00e9e mortelle malgr\u00e9 un traitement antifongique agressif [10].<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Comment_se_debarrasser_dEurotium\"><\/span>Comment se d\u00e9barrasser d\u2019<em>Eurotium<\/em>?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous avez d\u00e9tect\u00e9 de la moisissure quelle qu\u2019elle soit chez vous ou sur votre lieu de travail, vous en d\u00e9barrasser devrait \u00eatre votre premi\u00e8re priorit\u00e9. Bien qu\u2019il soit vrai que certaines esp\u00e8ces sont plus dangereuses que d\u2019autres, il est important de rappeler que la moisissure se d\u00e9veloppe en colonies mixtes, ce qui signifie que plusieurs moisissures dangereuses peuvent, \u00e0 moyen terme, appara\u00eetre. En dehors des moisissures cultiv\u00e9es en laboratoires, il est rare qu\u2019une prolif\u00e9ration de moisissures ne soit constitu\u00e9e que d\u2019une seule esp\u00e8ce. La pr\u00e9sence d\u2019un colonisateur primaire comme <em>Eurotium<\/em> est comme un appel \u00e0 d\u2019autres moisissures pour se d\u00e9velopper sur un habitat qui leur est d\u00e9sormais viable.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9liminer de petites colonies est un travail qui peut \u00eatre effectu\u00e9 par n\u2019importe qui. S\u2019occuper d\u2019infestations beaucoup plus grandes et profondes ne devrait cependant \u00eatre le travail que de professionnels. Les grosses infestations, en effet, sont typiquement caus\u00e9es par un probl\u00e8me d\u2019humidit\u00e9. Il ne s\u2019agit parfois que d\u2019un tuyau qui fuit ou une goutti\u00e8re bouch\u00e9e, mais il peut parfois provenir d\u2019un b\u00e2timent mal con\u00e7u, d\u2019un mauvais drainage des eaux de pluie ou d\u2019une mauvaise isolation. R\u00e9parer ces probl\u00e8mes peut donc s\u2019av\u00e9rer tr\u00e8s cher, et faire appel \u00e0 un <a href=\"https:\/\/fr.bustmold.com\/nos-services\/assainissement\/elimination-des-moisissures\/\">professionnel en d\u00e9contamination de la moisissure<\/a> vous permettra donc de d\u00e9tecter ces probl\u00e8mes avant que vous ne soyez oblig\u00e9 de d\u00e9penser des sommes beaucoup plus importantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mold Busters propose une large gamme de services li\u00e9s \u00e0 la moisissures, qui inclut des <a href=\"https:\/\/fr.bustmold.com\/nos-services\/analyses\/analyse-de-la-qualite-air\/\">tests de la qualit\u00e9 de l\u2019air int\u00e9rieur<\/a>, des services de d\u00e9shumidification, de <a href=\"https:\/\/fr.bustmold.com\/nos-services\/analyses\/analyse-de-moisissure\/\">test et d\u2019\u00e9limination de la moisissure<\/a>. Forts de nos 19 ans d\u2019exp\u00e9rience et des derni\u00e8res technologies d\u2019\u00e9limination de la moisissure, nous sommes capables de venir \u00e0 bout des infestations de moisissures de toutes tailles. Nos techniciens, par ailleurs, vous fournirons tous les conseils n\u00e9cessaires pour vous aider \u00e0 garder votre maison vierge de toute moisissure dans le futur. Appelez-nous d\u00e8s maintenant pour prendre rendez-vous.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"References\"><\/span>References<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Pitt JI, Hocking AD (2009). <em>Aspergillus<\/em> and Related Teleomorphs. In: Fungi and Food Spoilage. Springer, Boston, MA, pp 453.<\/li>\n\n\n\n<li>Bensch K (2019). Eurotium. Retrieved from <a href=\"http:\/\/www.mycobank.org\/Biolomics.aspx?Table=Mycobank&amp;Rec=47603&amp;Fields=All\" target=\"_blank\" rel=\"noreferrer noopener\">mycobank.org<\/a>.<\/li>\n\n\n\n<li>Howard DH (2003). Pathogenic Fungi in Humans and Animals. Marcel Dekker, New York. pp 240-498.<\/li>\n\n\n\n<li>Pitt JI, Samson RA (2007). Nomenclatural considerations in naming species of <em>Aspergillus<\/em> and its teleomorphs. Stud Mycol. 59:67\u201370.<\/li>\n\n\n\n<li>Butinar L, Zalar P, Frisvad JC, Gunde-Cimerman N (2005). The genus <em>Eurotium<\/em> \u2013 members of indigenous fungal community in hypersaline waters of salterns. FEMS Microbiol Ecol. 51(2):155-66.<\/li>\n\n\n\n<li>Greco M, Pardo A, Pose G, Patriarca A (2018). Effect of water activity and temperature on the growth of <em>Eurotium<\/em> species isolated from animal feeds. Rev Iberoam Micol. 35(1):39-48.<\/li>\n\n\n\n<li>Flannigan B, Samson RA, Miller JD (2011). Microorganisms in home and indoor work environments: diversity, health impacts, investigation and control. CRC Press. Boca Raton, FL. pp 55-107.<\/li>\n\n\n\n<li>Oshikata C, Watanabe M, Saito A, Ishida M, Kobayashi S, Konuma R, Kamata Y, Terajima J, Cho J, Yanai M, Tsurikisawa N (2017). Allergic Bronchopulmonary Mycosis due to Exposure to <em>Eurotium herbariorum<\/em> after the Great East Japan Earthquake. Prehosp Disaster Med. 32(6):688-690.<\/li>\n\n\n\n<li>Haverinen U, Husman T, Toivola M, Suonketo J, Pentti M, Lindberg R, Leinonen J, Hyv\u00e4rinen A, Meklin T, Nevalainen A (1999). An approach to management of critical indoor air problems in school buildings. Environ Health Perspect. 107 Suppl 3:509-14.<\/li>\n\n\n\n<li>Lacqua A, Tom J, Wong L, Dilliberto G (2016). Aspergillus Glaucus. Retrieved from <a href=\"https:\/\/microbewiki.kenyon.edu\/index.php\/Aspergillus_Glaucus\" target=\"_blank\" rel=\"noreferrer noopener\">microbewiki.kenyon.edu<\/a>.<\/li>\n<\/ol>\n\n\n\n<div class=\"wp-block-uagb-columns uagb-columns__wrap uagb-columns__background-color uagb-columns__stack-none uagb-columns__valign-center uagb-columns__gap-20 align uagb-block-5b67cdaf uagb-columns__columns-2 uagb-columns__max_width-theme\"><div class=\"uagb-columns__overlay\"><\/div><div class=\"uagb-columns__inner-wrap uagb-columns__columns-2\">\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-7f63cba9\"><div class=\"uagb-column__overlay\"><\/div>\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/www.bustmold.com\/wp-content\/uploads\/2023\/01\/mold-removal-guidelines-03-199x300.jpg\" alt=\"mold removal guidelines book cover 199\" class=\"wp-image-1588\"\/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-f3761127\"><div class=\"uagb-column__overlay\"><\/div>\n<p class=\"has-text-align-center has-ast-global-color-5-color has-text-color has-medium-font-size wp-block-paragraph\"><strong>Get Special Gift: <strong>Industry-Standard Mold Removal Guidelines<\/strong><\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-ast-global-color-0-color has-css-opacity has-ast-global-color-0-background-color has-background aligncenter\"\/>\n\n\n\n<p class=\"has-text-align-center has-ast-global-color-5-color has-text-color wp-block-paragraph\">Download the <strong>industry-standard guidelines<\/strong> that Mold Busters use in their own mold removal services, including news, tips and special offers:<\/p>\n\n\n<script type=\"text\/javascript\">var gform;gform||(document.addEventListener(\"gform_main_scripts_loaded\",function(){gform.scriptsLoaded=!0}),window.addEventListener(\"DOMContentLoaded\",function(){gform.domLoaded=!0}),gform={domLoaded:!1,scriptsLoaded:!1,initializeOnLoaded:function(o){gform.domLoaded&&gform.scriptsLoaded?o():!gform.domLoaded&&gform.scriptsLoaded?window.addEventListener(\"DOMContentLoaded\",o):document.addEventListener(\"gform_main_scripts_loaded\",o)},hooks:{action:{},filter:{}},addAction:function(o,n,r,t){gform.addHook(\"action\",o,n,r,t)},addFilter:function(o,n,r,t){gform.addHook(\"filter\",o,n,r,t)},doAction:function(o){gform.doHook(\"action\",o,arguments)},applyFilters:function(o){return gform.doHook(\"filter\",o,arguments)},removeAction:function(o,n){gform.removeHook(\"action\",o,n)},removeFilter:function(o,n,r){gform.removeHook(\"filter\",o,n,r)},addHook:function(o,n,r,t,i){null==gform.hooks[o][n]&&(gform.hooks[o][n]=[]);var e=gform.hooks[o][n];null==i&&(i=n+\"_\"+e.length),gform.hooks[o][n].push({tag:i,callable:r,priority:t=null==t?10:t})},doHook:function(n,o,r){var t;if(r=Array.prototype.slice.call(r,1),null!=gform.hooks[n][o]&&((o=gform.hooks[n][o]).sort(function(o,n){return o.priority-n.priority}),o.forEach(function(o){\"function\"!=typeof(t=o.callable)&&(t=window[t]),\"action\"==n?t.apply(null,r):r[0]=t.apply(null,r)})),\"filter\"==n)return r[0]},removeHook:function(o,n,t,i){var r;null!=gform.hooks[o][n]&&(r=(r=gform.hooks[o][n]).filter(function(o,n,r){return!!(null!=i&&i!=o.tag||null!=t&&t!=o.priority)}),gform.hooks[o][n]=r)}});<\/script>\n                <div class='gf_browser_gecko gform_wrapper gravity-theme gform-theme--no-framework' data-form-theme='gravity-theme' data-form-index='0' id='gform_wrapper_1' ><style>#gform_wrapper_1[data-form-index=\"0\"].gform-theme,[data-parent-form=\"1_0\"]{--gf-color-primary: #204ce5;--gf-color-primary-rgb: 32, 76, 229;--gf-color-primary-contrast: #fff;--gf-color-primary-contrast-rgb: 255, 255, 255;--gf-color-primary-darker: #001AB3;--gf-color-primary-lighter: #527EFF;--gf-color-secondary: #fff;--gf-color-secondary-rgb: 255, 255, 255;--gf-color-secondary-contrast: #112337;--gf-color-secondary-contrast-rgb: 17, 35, 55;--gf-color-secondary-darker: #F5F5F5;--gf-color-secondary-lighter: #FFFFFF;--gf-color-out-ctrl-light: rgba(17, 35, 55, 0.1);--gf-color-out-ctrl-light-rgb: 17, 35, 55;--gf-color-out-ctrl-light-darker: rgba(104, 110, 119, 0.35);--gf-color-out-ctrl-light-lighter: #F5F5F5;--gf-color-out-ctrl-dark: #585e6a;--gf-color-out-ctrl-dark-rgb: 88, 94, 106;--gf-color-out-ctrl-dark-darker: #112337;--gf-color-out-ctrl-dark-lighter: rgba(17, 35, 55, 0.65);--gf-color-in-ctrl: #fff;--gf-color-in-ctrl-rgb: 255, 255, 255;--gf-color-in-ctrl-contrast: #112337;--gf-color-in-ctrl-contrast-rgb: 17, 35, 55;--gf-color-in-ctrl-darker: #F5F5F5;--gf-color-in-ctrl-lighter: #FFFFFF;--gf-color-in-ctrl-primary: #204ce5;--gf-color-in-ctrl-primary-rgb: 32, 76, 229;--gf-color-in-ctrl-primary-contrast: #fff;--gf-color-in-ctrl-primary-contrast-rgb: 255, 255, 255;--gf-color-in-ctrl-primary-darker: #001AB3;--gf-color-in-ctrl-primary-lighter: #527EFF;--gf-color-in-ctrl-light: rgba(17, 35, 55, 0.1);--gf-color-in-ctrl-light-rgb: 17, 35, 55;--gf-color-in-ctrl-light-darker: rgba(104, 110, 119, 0.35);--gf-color-in-ctrl-light-lighter: #F5F5F5;--gf-color-in-ctrl-dark: #585e6a;--gf-color-in-ctrl-dark-rgb: 88, 94, 106;--gf-color-in-ctrl-dark-darker: #112337;--gf-color-in-ctrl-dark-lighter: rgba(17, 35, 55, 0.65);--gf-radius: 3px;--gf-font-size-secondary: 14px;--gf-font-size-tertiary: 13px;--gf-icon-ctrl-number: url(\"data:image\/svg+xml,%3Csvg width='8' height='14' viewBox='0 0 8 14' fill='none' xmlns='http:\/\/www.w3.org\/2000\/svg'%3E%3Cpath fill-rule='evenodd' clip-rule='evenodd' d='M4 0C4.26522 5.96046e-08 4.51957 0.105357 4.70711 0.292893L7.70711 3.29289C8.09763 3.68342 8.09763 4.31658 7.70711 4.70711C7.31658 5.09763 6.68342 5.09763 6.29289 4.70711L4 2.41421L1.70711 4.70711C1.31658 5.09763 0.683417 5.09763 0.292893 4.70711C-0.0976311 4.31658 -0.097631 3.68342 0.292893 3.29289L3.29289 0.292893C3.48043 0.105357 3.73478 0 4 0ZM0.292893 9.29289C0.683417 8.90237 1.31658 8.90237 1.70711 9.29289L4 11.5858L6.29289 9.29289C6.68342 8.90237 7.31658 8.90237 7.70711 9.29289C8.09763 9.68342 8.09763 10.3166 7.70711 10.7071L4.70711 13.7071C4.31658 14.0976 3.68342 14.0976 3.29289 13.7071L0.292893 10.7071C-0.0976311 10.3166 -0.0976311 9.68342 0.292893 9.29289Z' fill='rgba(17, 35, 55, 0.65)'\/%3E%3C\/svg%3E\");--gf-icon-ctrl-select: url(\"data:image\/svg+xml,%3Csvg width='10' height='6' viewBox='0 0 10 6' fill='none' xmlns='http:\/\/www.w3.org\/2000\/svg'%3E%3Cpath fill-rule='evenodd' clip-rule='evenodd' d='M0.292893 0.292893C0.683417 -0.097631 1.31658 -0.097631 1.70711 0.292893L5 3.58579L8.29289 0.292893C8.68342 -0.0976311 9.31658 -0.0976311 9.70711 0.292893C10.0976 0.683417 10.0976 1.31658 9.70711 1.70711L5.70711 5.70711C5.31658 6.09763 4.68342 6.09763 4.29289 5.70711L0.292893 1.70711C-0.0976311 1.31658 -0.0976311 0.683418 0.292893 0.292893Z' fill='rgba(17, 35, 55, 0.65)'\/%3E%3C\/svg%3E\");--gf-icon-ctrl-search: url(\"data:image\/svg+xml,%3Csvg version='1.1' xmlns='http:\/\/www.w3.org\/2000\/svg' width='640' height='640'%3E%3Cpath d='M256 128c-70.692 0-128 57.308-128 128 0 70.691 57.308 128 128 128 70.691 0 128-57.309 128-128 0-70.692-57.309-128-128-128zM64 256c0-106.039 85.961-192 192-192s192 85.961 192 192c0 41.466-13.146 79.863-35.498 111.248l154.125 154.125c12.496 12.496 12.496 32.758 0 45.254s-32.758 12.496-45.254 0L367.248 412.502C335.862 434.854 297.467 448 256 448c-106.039 0-192-85.962-192-192z' fill='rgba(17, 35, 55, 0.65)'\/%3E%3C\/svg%3E\");--gf-label-space-y-secondary: var(--gf-label-space-y-md-secondary);--gf-ctrl-border-color: #686e77;--gf-ctrl-size: var(--gf-ctrl-size-md);--gf-ctrl-label-color-primary: #112337;--gf-ctrl-label-color-secondary: #112337;--gf-ctrl-choice-size: var(--gf-ctrl-choice-size-md);--gf-ctrl-checkbox-check-size: var(--gf-ctrl-checkbox-check-size-md);--gf-ctrl-radio-check-size: var(--gf-ctrl-radio-check-size-md);--gf-ctrl-btn-font-size: var(--gf-ctrl-btn-font-size-md);--gf-ctrl-btn-padding-x: var(--gf-ctrl-btn-padding-x-md);--gf-ctrl-btn-size: var(--gf-ctrl-btn-size-md);--gf-ctrl-btn-border-color-secondary: #686e77;--gf-ctrl-file-btn-bg-color-hover: #EBEBEB;--gf-field-pg-steps-number-color: rgba(17, 35, 55, 0.8);}<\/style><div id='gf_1' class='gform_anchor' tabindex='-1'><\/div><form method='post' enctype='multipart\/form-data' target='gform_ajax_frame_1' id='gform_1'  action='\/fr\/wp-json\/wp\/v2\/pages\/590#gf_1' data-formid='1' novalidate>\n                        <div class='gform-body gform_body'><div id='gform_fields_1' class='gform_fields top_label form_sublabel_below description_below'><fieldset id=\"field_1_1\" class=\"gfield gfield--type-name gfield--width-half gfield_contains_required field_sublabel_hidden_label gfield--no-description field_description_below hidden_label gfield_visibility_visible\"  data-js-reload=\"field_1_1\" ><legend class='gfield_label gform-field-label gfield_label_before_complex' >Name<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_text\">(N\u00e9cessaire)<\/span><\/span><\/legend><div class='ginput_complex ginput_container ginput_container--name no_prefix has_first_name no_middle_name no_last_name no_suffix gf_name_has_1 ginput_container_name gform-grid-row' id='input_1_1'>\n                            \n                            <span id='input_1_1_3_container' class='name_first gform-grid-col gform-grid-col--size-auto' >\n                                                    <input type='text' name='input_1.3' id='input_1_1_3' value=''   aria-required='true'   placeholder='Your Name'  \/>\n                                                    <label for='input_1_1_3' class='gform-field-label gform-field-label--type-sub hidden_sub_label screen-reader-text'>Pr\u00e9nom<\/label>\n                                                <\/span>\n                            \n                            \n                            \n                        <\/div><\/fieldset><div id=\"field_1_2\" class=\"gfield gfield--type-email gfield--width-half field_sublabel_below gfield--no-description field_description_below hidden_label gfield_visibility_visible\"  data-js-reload=\"field_1_2\" ><label class='gfield_label gform-field-label' for='input_1_2'>Email<\/label><div class='ginput_container ginput_container_email'>\n                            <input name='input_2' id='input_1_2' type='email' value='' class='large'   placeholder='Your E-mail'  aria-invalid=\"false\"  \/>\n                        <\/div><\/div><\/div><\/div>\n        <div class='gform_footer top_label'> <input type='submit' id='gform_submit_button_1' class='gform_button button' value='Sign Up!'  onclick='if(window[\"gf_submitting_1\"]){return false;}  if( !jQuery(\"#gform_1\")[0].checkValidity || jQuery(\"#gform_1\")[0].checkValidity()){window[\"gf_submitting_1\"]=true;}  ' onkeypress='if( event.keyCode == 13 ){ if(window[\"gf_submitting_1\"]){return false;} if( !jQuery(\"#gform_1\")[0].checkValidity || jQuery(\"#gform_1\")[0].checkValidity()){window[\"gf_submitting_1\"]=true;}  jQuery(\"#gform_1\").trigger(\"submit\",[true]); }' \/> <input type='hidden' name='gform_ajax' value='form_id=1&amp;title=&amp;description=&amp;tabindex=0&amp;theme=data-form-theme=&#039;gravity-theme&#039;' \/>\n            <input type='hidden' class='gform_hidden' name='is_submit_1' value='1' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submit' value='1' \/>\n            \n            <input type='hidden' class='gform_hidden' name='gform_unique_id' value='' \/>\n            <input type='hidden' class='gform_hidden' name='state_1' value='WyJbXSIsIjBkMTA0NThmNTBiMGU1ZmYxMDhhMmFmMjM3YjhlZjFkIl0=' \/>\n            <input type='hidden' class='gform_hidden' name='gform_target_page_number_1' id='gform_target_page_number_1' value='0' \/>\n            <input type='hidden' class='gform_hidden' name='gform_source_page_number_1' id='gform_source_page_number_1' value='1' \/>\n            <input type='hidden' name='gform_field_values' value='' \/>\n            \n        <\/div>\n                        <p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"ak_\"><label>&#916;<textarea name=\"ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"ak_js\" value=\"186\"\/><script>document.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );<\/script><\/p><\/form>\n                        <\/div>\n\t\t                <iframe style='display:none;width:0px;height:0px;' src='about:blank' name='gform_ajax_frame_1' id='gform_ajax_frame_1' title='Cette iframe contient la logique n\u00e9cessaire pour manipuler Gravity Forms avec Ajax.'><\/iframe>\n\t\t                <script>\ngform.initializeOnLoaded( function() {gformInitSpinner( 1, 'https:\/\/library.bustmold.com\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery('#gform_ajax_frame_1').on('load',function(){var contents = jQuery(this).contents().find('*').html();var is_postback = contents.indexOf('GF_AJAX_POSTBACK') >= 0;if(!is_postback){return;}var form_content = jQuery(this).contents().find('#gform_wrapper_1');var is_confirmation = jQuery(this).contents().find('#gform_confirmation_wrapper_1').length > 0;var is_redirect = contents.indexOf('gformRedirect(){') >= 0;var is_form = form_content.length > 0 && ! is_redirect && ! is_confirmation;var mt = parseInt(jQuery('html').css('margin-top'), 10) + parseInt(jQuery('body').css('margin-top'), 10) + 100;if(is_form){jQuery('#gform_wrapper_1').html(form_content.html());if(form_content.hasClass('gform_validation_error')){jQuery('#gform_wrapper_1').addClass('gform_validation_error');} else {jQuery('#gform_wrapper_1').removeClass('gform_validation_error');}setTimeout( function() { \/* delay the scroll by 50 milliseconds to fix a bug in chrome *\/ jQuery(document).scrollTop(jQuery('#gform_wrapper_1').offset().top - mt); }, 50 );if(window['gformInitDatepicker']) {gformInitDatepicker();}if(window['gformInitPriceFields']) {gformInitPriceFields();}var current_page = jQuery('#gform_source_page_number_1').val();gformInitSpinner( 1, 'https:\/\/library.bustmold.com\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery(document).trigger('gform_page_loaded', [1, current_page]);window['gf_submitting_1'] = false;}else if(!is_redirect){var confirmation_content = jQuery(this).contents().find('.GF_AJAX_POSTBACK').html();if(!confirmation_content){confirmation_content = contents;}setTimeout(function(){jQuery('#gform_wrapper_1').replaceWith(confirmation_content);jQuery(document).scrollTop(jQuery('#gf_1').offset().top - mt);jQuery(document).trigger('gform_confirmation_loaded', [1]);window['gf_submitting_1'] = false;wp.a11y.speak(jQuery('#gform_confirmation_message_1').text());}, 50);}else{jQuery('#gform_1').append(contents);if(window['gformRedirect']) {gformRedirect();}}jQuery(document).trigger('gform_post_render', [1, current_page]);gform.utils.trigger({ event: 'gform\/postRender', native: false, data: { formId: 1, currentPage: current_page } });} );} );\n<\/script>\n<\/div>\n<\/div><\/div>\n\n<hr class=\"wp-block-separator has-text-color has-luminous-vivid-orange-color has-css-opacity has-luminous-vivid-orange-background-color has-background aligncenter\"\/>\n\n<section class=\"wp-block-uagb-columns uagb-columns__wrap uagb-columns__background-none uagb-columns__stack-mobile uagb-columns__valign-center uagb-columns__gap-10 align uagb-block-ee9510ba uagb-columns__columns-4 uagb-columns__max_width-theme\"><div class=\"uagb-columns__overlay\"><\/div><div class=\"uagb-columns__inner-wrap uagb-columns__columns-4\">\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-bfa5bb58\"><div class=\"uagb-column__overlay\"><\/div>\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/www.bustmold.com\/wp-content\/uploads\/2023\/09\/John-Ward.jpg\" alt=\"\" style=\"width:150px;height:150px\"\/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-386b1178\"><div class=\"uagb-column__overlay\"><\/div>\n<p class=\"has-text-align-center wp-block-paragraph\"><strong>Written by:<\/strong><br\/><a href=\"https:\/\/www.bustmold.com\/about-us\/our-team\/john-ward\/\">John Ward<\/a><br\/>Account Executive<br\/>Mold Busters<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-ba032752\"><div class=\"uagb-column__overlay\"><\/div>\n<p class=\"has-text-align-center wp-block-paragraph\"><strong>Fact checked by:<\/strong><br\/><a href=\"https:\/\/www.bustmold.com\/about-us\/our-team\/\">Michael Golubev<\/a><br\/>General Manager<br\/>Mold Busters<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-576699a5\"><div class=\"uagb-column__overlay\"><\/div>\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/www.bustmold.com\/wp-content\/uploads\/2023\/09\/michael-g.jpg\" alt=\"\" style=\"width:150px;height:150px\"\/><\/figure>\n<\/div>\n<\/div><\/section>\n","protected":false},"excerpt":{"rendered":"<p>La plupart des esp\u00e8ces de champignons ont des cycles de vie compliqu\u00e9s, pl\u00e9omorphes. Cela signifie donc qu\u2019ils peuvent exister sous deux formes, une forme anamorphe, au cours de laquelle il se reproduit asexuellement et produit des copies de lui-m\u00eame g\u00e9n\u00e9tiquement identiques, et une forme t\u00e9l\u00e9omorphe qui appara\u00eet lorsque deux champignons g\u00e9n\u00e9tiquement compatibles fusionnent et produit &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/library.bustmold.com\/fr\/eurotium\/\"> <span class=\"screen-reader-text\">Eurotium<\/span> Lire la suite \u00bb<\/a><\/p>\n","protected":false},"author":1,"featured_media":592,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"_uag_custom_page_level_css":"","site-sidebar-layout":"","site-content-layout":"","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","footnotes":""},"tags":[],"class_list":["post-590","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Eurotium: quelle est cette moisissure, quels sont ses dangers?<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez tout sur la moisissure Eurotium: les propri\u00e9t\u00e9s de ce champignon, les dangers qu&#039;il repr\u00e9sente, et comment s&#039;en d\u00e9barrasser gr\u00e2ce \u00e0 notre aide.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/library.bustmold.com\/fr\/eurotium\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eurotium: quelle est cette moisissure, quels sont ses dangers?\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez tout sur la moisissure Eurotium: les propri\u00e9t\u00e9s de ce champignon, les dangers qu&#039;il repr\u00e9sente, et comment s&#039;en d\u00e9barrasser gr\u00e2ce \u00e0 notre aide.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/library.bustmold.com\/fr\/eurotium\/\" \/>\n<meta property=\"og:site_name\" content=\"Mold Library\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-22T15:30:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bustmold.com\/wp-content\/uploads\/2019\/07\/eurotium-2.jpg\" \/><meta property=\"og:image\" content=\"https:\/\/www.bustmold.com\/wp-content\/uploads\/2019\/07\/eurotium-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.bustmold.com\/wp-content\/uploads\/2019\/07\/eurotium-2.jpg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/library.bustmold.com\/fr\/eurotium\/\",\"url\":\"https:\/\/library.bustmold.com\/fr\/eurotium\/\",\"name\":\"Eurotium: quelle est cette moisissure, quels sont ses dangers?\",\"isPartOf\":{\"@id\":\"https:\/\/library.bustmold.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/library.bustmold.com\/fr\/eurotium\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/library.bustmold.com\/fr\/eurotium\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/www.bustmold.com\/wp-content\/uploads\/2019\/07\/eurotium-2.jpg?w=1200&resize=1200,630&ssl=1\",\"datePublished\":\"2022-05-17T13:43:48+00:00\",\"dateModified\":\"2023-12-22T15:30:38+00:00\",\"description\":\"D\u00e9couvrez tout sur la moisissure Eurotium: les propri\u00e9t\u00e9s de ce champignon, les dangers qu'il repr\u00e9sente, et comment s'en d\u00e9barrasser gr\u00e2ce \u00e0 notre aide.\",\"breadcrumb\":{\"@id\":\"https:\/\/library.bustmold.com\/fr\/eurotium\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/library.bustmold.com\/fr\/eurotium\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/library.bustmold.com\/fr\/eurotium\/#primaryimage\",\"url\":\"https:\/\/i0.wp.com\/www.bustmold.com\/wp-content\/uploads\/2019\/07\/eurotium-2.jpg?w=1200&resize=1200,630&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/www.bustmold.com\/wp-content\/uploads\/2019\/07\/eurotium-2.jpg?w=1200&resize=1200,630&ssl=1\",\"width\":\"1200\",\"height\":\"630\",\"caption\":\"Eurotium\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/library.bustmold.com\/fr\/eurotium\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Mold Library\",\"item\":\"https:\/\/library.bustmold.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eurotium\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/library.bustmold.com\/fr\/#website\",\"url\":\"https:\/\/library.bustmold.com\/fr\/\",\"name\":\"Mold Library\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/library.bustmold.com\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/library.bustmold.com\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/library.bustmold.com\/fr\/#organization\",\"name\":\"Mold Busters\",\"url\":\"https:\/\/library.bustmold.com\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/library.bustmold.com\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/library.bustmold.com\/wp-content\/uploads\/2022\/05\/mold-busters-logo.svg\",\"contentUrl\":\"https:\/\/library.bustmold.com\/wp-content\/uploads\/2022\/05\/mold-busters-logo.svg\",\"width\":794,\"height\":313,\"caption\":\"Mold Busters\"},\"image\":{\"@id\":\"https:\/\/library.bustmold.com\/fr\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Eurotium: quelle est cette moisissure, quels sont ses dangers?","description":"D\u00e9couvrez tout sur la moisissure Eurotium: les propri\u00e9t\u00e9s de ce champignon, les dangers qu'il repr\u00e9sente, et comment s'en d\u00e9barrasser gr\u00e2ce \u00e0 notre aide.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/library.bustmold.com\/fr\/eurotium\/","og_locale":"fr_FR","og_type":"article","og_title":"Eurotium: quelle est cette moisissure, quels sont ses dangers?","og_description":"D\u00e9couvrez tout sur la moisissure Eurotium: les propri\u00e9t\u00e9s de ce champignon, les dangers qu'il repr\u00e9sente, et comment s'en d\u00e9barrasser gr\u00e2ce \u00e0 notre aide.","og_url":"https:\/\/library.bustmold.com\/fr\/eurotium\/","og_site_name":"Mold Library","article_modified_time":"2023-12-22T15:30:38+00:00","og_image":[{"url":"https:\/\/www.bustmold.com\/wp-content\/uploads\/2019\/07\/eurotium-2.jpg"},{"width":"1200","height":"630","url":"https:\/\/www.bustmold.com\/wp-content\/uploads\/2019\/07\/eurotium-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/www.bustmold.com\/wp-content\/uploads\/2019\/07\/eurotium-2.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/library.bustmold.com\/fr\/eurotium\/","url":"https:\/\/library.bustmold.com\/fr\/eurotium\/","name":"Eurotium: quelle est cette moisissure, quels sont ses dangers?","isPartOf":{"@id":"https:\/\/library.bustmold.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/library.bustmold.com\/fr\/eurotium\/#primaryimage"},"image":{"@id":"https:\/\/library.bustmold.com\/fr\/eurotium\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.bustmold.com\/wp-content\/uploads\/2019\/07\/eurotium-2.jpg?w=1200&resize=1200,630&ssl=1","datePublished":"2022-05-17T13:43:48+00:00","dateModified":"2023-12-22T15:30:38+00:00","description":"D\u00e9couvrez tout sur la moisissure Eurotium: les propri\u00e9t\u00e9s de ce champignon, les dangers qu'il repr\u00e9sente, et comment s'en d\u00e9barrasser gr\u00e2ce \u00e0 notre aide.","breadcrumb":{"@id":"https:\/\/library.bustmold.com\/fr\/eurotium\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/library.bustmold.com\/fr\/eurotium\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/library.bustmold.com\/fr\/eurotium\/#primaryimage","url":"https:\/\/i0.wp.com\/www.bustmold.com\/wp-content\/uploads\/2019\/07\/eurotium-2.jpg?w=1200&resize=1200,630&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.bustmold.com\/wp-content\/uploads\/2019\/07\/eurotium-2.jpg?w=1200&resize=1200,630&ssl=1","width":"1200","height":"630","caption":"Eurotium"},{"@type":"BreadcrumbList","@id":"https:\/\/library.bustmold.com\/fr\/eurotium\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Mold Library","item":"https:\/\/library.bustmold.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Eurotium"}]},{"@type":"WebSite","@id":"https:\/\/library.bustmold.com\/fr\/#website","url":"https:\/\/library.bustmold.com\/fr\/","name":"Mold Library","description":"","publisher":{"@id":"https:\/\/library.bustmold.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/library.bustmold.com\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/library.bustmold.com\/fr\/#organization","name":"Mold Busters","url":"https:\/\/library.bustmold.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/library.bustmold.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/library.bustmold.com\/wp-content\/uploads\/2022\/05\/mold-busters-logo.svg","contentUrl":"https:\/\/library.bustmold.com\/wp-content\/uploads\/2022\/05\/mold-busters-logo.svg","width":794,"height":313,"caption":"Mold Busters"},"image":{"@id":"https:\/\/library.bustmold.com\/fr\/#\/schema\/logo\/image\/"}}]}},"uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/www.bustmold.com\/wp-content\/uploads\/2019\/07\/eurotium-2.jpg?w=1200&resize=1200,630&ssl=1",1200,630,false],"thumbnail":["https:\/\/i0.wp.com\/www.bustmold.com\/wp-content\/uploads\/2019\/07\/eurotium-2.jpg?w=150&resize=150,150&ssl=1",150,150,false],"medium":["https:\/\/i0.wp.com\/www.bustmold.com\/wp-content\/uploads\/2019\/07\/eurotium-2.jpg?w=300&resize=300,300&ssl=1",300,300,false],"medium_large":["https:\/\/i0.wp.com\/www.bustmold.com\/wp-content\/uploads\/2019\/07\/eurotium-2.jpg?w=768&resize=768,0&ssl=1",768,0,false],"large":["https:\/\/i0.wp.com\/www.bustmold.com\/wp-content\/uploads\/2019\/07\/eurotium-2.jpg?w=1024&resize=1024,1024&ssl=1",1024,1024,false],"1536x1536":["https:\/\/i0.wp.com\/www.bustmold.com\/wp-content\/uploads\/2019\/07\/eurotium-2.jpg?w=1536&resize=1536,1536&ssl=1",1536,1536,false],"2048x2048":["https:\/\/i0.wp.com\/www.bustmold.com\/wp-content\/uploads\/2019\/07\/eurotium-2.jpg?w=2048&resize=2048,2048&ssl=1",2048,2048,false]},"uagb_author_info":{"display_name":"mblibrary","author_link":"https:\/\/library.bustmold.com\/fr\/author\/mblibrary\/"},"uagb_comment_info":0,"uagb_excerpt":"La plupart des esp\u00e8ces de champignons ont des cycles de vie compliqu\u00e9s, pl\u00e9omorphes. Cela signifie donc qu\u2019ils peuvent exister sous deux formes, une forme anamorphe, au cours de laquelle il se reproduit asexuellement et produit des copies de lui-m\u00eame g\u00e9n\u00e9tiquement identiques, et une forme t\u00e9l\u00e9omorphe qui appara\u00eet lorsque deux champignons g\u00e9n\u00e9tiquement compatibles fusionnent et produit\u2026","_links":{"self":[{"href":"https:\/\/library.bustmold.com\/fr\/wp-json\/wp\/v2\/pages\/590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/library.bustmold.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/library.bustmold.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/library.bustmold.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/library.bustmold.com\/fr\/wp-json\/wp\/v2\/comments?post=590"}],"version-history":[{"count":3,"href":"https:\/\/library.bustmold.com\/fr\/wp-json\/wp\/v2\/pages\/590\/revisions"}],"predecessor-version":[{"id":1816,"href":"https:\/\/library.bustmold.com\/fr\/wp-json\/wp\/v2\/pages\/590\/revisions\/1816"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/library.bustmold.com\/fr\/wp-json\/wp\/v2\/media\/592"}],"wp:attachment":[{"href":"https:\/\/library.bustmold.com\/fr\/wp-json\/wp\/v2\/media?parent=590"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/library.bustmold.com\/fr\/wp-json\/wp\/v2\/tags?post=590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}